{"id":324696,"date":"2024-07-10T08:32:59","date_gmt":"2024-07-10T15:32:59","guid":{"rendered":"https:\/\/www.paloaltonetworks.com\/blog\/?p=324696"},"modified":"2024-07-10T08:41:56","modified_gmt":"2024-07-10T15:41:56","slug":"forrester-names-palo-alto-networks-a-leader-in-xdr","status":"publish","type":"post","link":"https:\/\/www2.paloaltonetworks.com\/blog\/2024\/07\/forrester-names-palo-alto-networks-a-leader-in-xdr\/?lang=de","title":{"rendered":"Forrester benennt Palo Alto Networks als Leader bei XDR"},"content":{"rendered":"<h3>Mit Cortex\u00a0XDR wird Palo Alto Networks im Forrester Wave-Bericht 2024 f\u00fcr Extended-Detection-and-Response-Plattformen als Leader aufgef\u00fchrt.<\/h3>\n<p>Seit unser Gr\u00fcnder Nir Zuk vor fast sechs Jahren den Begriff \u201eExtended Detection and Response\u201d (Erweiterte Bedrohungserkennung und -abwehr) pr\u00e4gte, arbeiten wir daran, XDR als Grundlage des modernen Sicherheitsbetriebs zu etablieren. SecOps-Teams spielen eine zentrale Rolle beim Schutz ihrer Organisationen vor Angreifern. Doch viele geraten dabei immer wieder ins Hintertreffen, weil sie regelrecht von Alarmen \u00fcberflutet werden, denen sie mit verschiedenen komplizierten Sicherheitsprodukten nachgehen m\u00fcssen. XDR-Plattformen erkennen automatisch Verhaltensweisen, die auf Angriffe hindeuten k\u00f6nnten, und geben den Analysten in den SecOps-Teams zudem konkrete Empfehlungen f\u00fcr die Behebung dieser potenziell gef\u00e4hrlichen Vorf\u00e4lle.<\/p>\n<p><strong>Heute freuen wir uns, bekanntgeben zu k\u00f6nnen, dass Cortex\u00a0XDR im Bericht \u201eThe Forrester Wave\u2122: Extended Detection and Response (XDR) Platforms, Q2 2024\u201d<\/strong>\u00a0als Leader eingestuft wurde und mehrere Anerkennungen erhielt:<\/p>\n<ul>\n<li><strong>Innovationskraft (\u201eCommitment to Disruption\u201c)<\/strong>\u00a0\u2013 Wir investieren in Forschung und Entwicklung und stellen kontinuierlich qualitativ hochwertige Features bereit.<\/li>\n<li><strong>Unterst\u00fctzung von Analysten (\u201eEmpowering Analysts\u201c)<\/strong>\u00a0\u2013 Cortex\u00a0XDR erm\u00f6glicht dadurch eine effektive Erkennung und Abwehr.<\/li>\n<li><strong>Erweiterungen (\u201eEnhancements\u201c)<\/strong>\u00a0\u2013 Wir stellen erweiterte Plattformfunktionen und Analysen f\u00fcr Identit\u00e4ten und die Cloud in den Mittelpunkt.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/start.paloaltonetworks.com\/2024-forrester-xdr-wave-leader\"><img loading=\"lazy\" decoding=\"async\"  class=\"wp-image-321972 size-full alignleft lozad lozad\"  data-src=\"\/blog\/wp-content\/uploads\/2024\/06\/cortex-xdr_forrester-wave-report-2024_blog2_400x300-1.png\" alt=\"Forrester Wave Leader 2024 XDR\" width=\"202\" height=\"203\" data-src=\"\/blog\/wp-content\/uploads\/2024\/06\/cortex-xdr_forrester-wave-report-2024_blog2_400x300-1.png\" data-loaded=\"true\" \/><\/a><\/p>\n<p>F\u00fcr uns best\u00e4tigt die Anerkennung in diesem Forrester Wave-Bericht den Erfolg, den SecOps-Team mit unserer Cortex-Plattform erzielen konnten, und demonstriert unser kontinuierliches Engagement bez\u00fcglich der Unterst\u00fctzung von Kunden bei der proaktiven Cyberabwehr. Wir m\u00f6chten allen Kunden, die Cortex\u00a0XDR den Schutz ihrer Organisation anvertrauen, ein gro\u00dfes Danke f\u00fcr ihr Engagement und ihre Partnerschaft aussprechen.<\/p>\n<p><a href=\"https:\/\/start.paloaltonetworks.com\/2024-forrester-xdr-wave-leader\">Vollst\u00e4ndigen Bericht lesen<\/a><\/p>\n<h2><a id=\"post-321685-_gjdgxs\"><\/a>The Forrester Wave for Extended Detection and Response Platforms<\/h2>\n<p>Forrester Wave-Evaluierungen sollen Kunden dabei helfen, fundierte Entscheidungen bei der Anschaffung von Technologiel\u00f6sungen zu treffen. Die Analysten bei Forrester bewerten alle Anbieter danach, wie stark ihr Angebot, ihre Strategie und ihre Marktpr\u00e4senz ist. Die Bewertung selbst basiert auf einer ausgiebigen Analyse jedes dieser Bereiche sowie einer Produktdemonstration und direkten \u00c4u\u00dferungen ausgew\u00e4hlter Kunden.<\/p>\n<p>Jeder Bewertungsbereich erh\u00e4lt eine Note, sodass Kunden jedes einzelne Kriterium quantitativ auswerten und die Ergebnisse mit denen anderer Anbieter vergleichen k\u00f6nnen. Cortex\u00a0XDR hat die beste m\u00f6gliche Note erhalten: 5 von 5 in den meisten bewerteten Kriterien. Forrester beschreibt einen Wert von 5 als \u201eanderen Produkten in dieser Bewertung \u00fcberlegen\u201d. Einige Bereiche sind hier besonders erw\u00e4hnenswert:<\/p>\n<ul>\n<li><strong>Vision (5\/5)\u00a0\u2013\u00a0<\/strong>Unsere Vision f\u00fcr Cortex\u00a0XDR ist es, die richtigen Voraussetzungen f\u00fcr die SecOps-Transformation zu schaffen, einen branchenf\u00fchrenden, pr\u00e4ventionsorientierten Ansatz f\u00fcr die Sicherheit am Endpunkt umzusetzen, mit KI-basierten Analysen die Verantwortung f\u00fcr die Erkennung und Abwehr zu \u00fcbernehmen und die Konsolidierung in einer zentralen SOC-Plattform zu erm\u00f6glichen.<\/li>\n<li><strong>KI und maschinelles Lernen (5\/5)\u00a0\u2013<\/strong>\u00a0Cortex\u00a0XDR nutzt Tausende von maschinellen Lernmodellen f\u00fcr die Bedrohungspr\u00e4vention und \u2011erkennung, die Einsch\u00e4tzung der mit Benutzern und Objekten verbundenen Risiken sowie die Vorfallspriorisierung anhand von Daten aus allen integrierten Quellen.<\/li>\n<li><strong>Endpunktschutz (5\/5)\u00a0\u2013<\/strong>\u00a0Cortex\u00a0XDR koordiniert Pr\u00e4vention, Erkennung und Abwehr von einer zentralen Konsole aus\u00a0\u2013 mit vorkonfigurierten Pr\u00e4ventionsprofilen, die sofortigen Schutz vor raffinierten Bedrohungen bieten.<\/li>\n<li><strong>Innovation (5\/5)<\/strong>\u00a0\u2013 Unser Innovationsansatz f\u00fcr Cortex\u00a0XDR basiert auf einem tiefgreifenden Verst\u00e4ndnis der Anforderungen und Herausforderungen des SecOps-Bereichs und hat kontinuierliche Verbesserungen zur Folge, mit denen Kunden Angreifern immer einen Schritt voraus bleiben k\u00f6nnen.<\/li>\n<li><strong>Zus\u00e4tzliche Erkennungsoberfl\u00e4chen (5\/5)<\/strong>\u00a0\u2013 Cortex\u00a0XDR importiert, normalisiert und analysiert ein breites Spektrum an unternehmensinternen Daten und Drittanbieterdaten f\u00fcr die Erkennung\u00a0\u2013 von Netzwerksicherheitsprodukten, Cloud-Anbietern, Identit\u00e4tssystemen und aus vielen anderen Quellen.<\/li>\n<\/ul>\n<p>Cortex\u00a0XDR hat auch in folgenden Bereichen eine Bewertung von 5\/5 erhalten: Abwehr, Bedrohungssuche, administrative Kontrolle, Analystenerfahrung, Bereitstellungsmodell, Schulung und Community.<\/p>\n<h2><a id=\"post-321685-_30j0zll\"><\/a>Warum XDR unserer Meinung nach eine gute Grundlage f\u00fcr moderne SecOps ist<\/h2>\n<blockquote><p>Die Vision des Unternehmens\u00a0\u2013 eine Welt zu schaffen, in der jeder Tag sicherer ist als der Tag zuvor\u00a0\u2013 spiegelt sich in seinen Produkten in Form eines pr\u00e4ventionsbasierten Ansatzes und der Unterst\u00fctzung von Analysten bei der effektiven Erkennung und Abwehr wider.<\/p><\/blockquote>\n<p><em>\u2013 The Forrester Wave\u2122: Extended Detection And Response Platforms, Q2 2024\u201c<\/em><\/p>\n<p>Wir verstehen, wie anstrengend die Arbeit im SecOps-Bereich sein kann\u00a0\u2013 die \u00fcberw\u00e4ltigende Geschwindigkeit der Bedrohungsentwicklung, die schiere Anzahl an False Positives und die stetige Integration neuer Produkte in das SOC sind eine st\u00e4ndige Belastung. Daher haben Sicherheitsprofis oft das Gef\u00fchl, immer hinterherzuhinken. Hier setzen wir an, um sie bestm\u00f6glich zu unterst\u00fctzen. Unsere Vision f\u00fcr Cortex\u00a0XDR umfasst einen kompletten Paradigmenwechsel weg von dieser Realit\u00e4t.<\/p>\n<p>Dazu nutzen wir einen pr\u00e4ventionsorientieren Ansatz f\u00fcr die Endpunktsicherheit, damit wir den besten Schutz vor allen denkbaren Angriffsvektoren bieten k\u00f6nnen. Durch die kontinuierliche \u00dcberwachung und Vorhersage von Angreifertechniken entwickeln wir Schutzma\u00dfnahmen, anhand derer Kunden den Gro\u00dfteil der Angriffsszenarien vereiteln k\u00f6nnen, bevor ihre Infrastruktur infiltriert wird.<\/p>\n<p>Das SOC-Team kann Cortex\u00a0XDR als zentrales Transparenz-, Erkennungs- und Abwehrtool nutzen und Daten aus Endpunkten, Netzwerkfirewalls, Cloud-Sicherheitsdiensten, Identit\u00e4tsanbietern und anderen Drittanbieterquellen einbeziehen. Wir \u00fcbernehmen die \u00dcberwachung des weltweiten Angreiferverhaltens und trainieren unsere ML-Modelle, damit Kunden Bedrohungen blitzschnell erkennen k\u00f6nnen. Sowohl unsere Pr\u00e4ventions- als auch unsere Erkennungsanalysen wurden in der\u00a0<a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2023\/09\/mitre-engenuity-attck-evaluations-results\/\">aktuellen MITRE\u00a0Engenuity-Evaluierung<\/a>\u00a0getestet und Cortex\u00a0XDR erzielte 100\u00a0% f\u00fcr beide Bereiche\u00a0\u2013 ohne Konfigurations\u00e4nderungen.<\/p>\n<p>Mit XDR erh\u00e4lt das SOC-Team einen umfassenden \u00dcberblick \u00fcber den gesamten Angriffsverlauf und seine Ursachen und kann so pr\u00e4zise Behebungsma\u00dfnahmen einleiten. Das hat weitreichende Konsequenzen, denn XDR kann nicht nur erheblich mehr Daten in Echtzeit analysieren als ein Team menschlicher Analysten, sondern zudem mithilfe von KI-Algorithmen Bedrohungen identifizieren. Schon allein deshalb stellt XDR einen deutlichen Fortschritt im Sicherheitsbereich dar.<\/p>\n<p>Dar\u00fcber hinaus sind wir davon \u00fcberzeugt, dass Cortex\u00a0XDR die Grundlage des modernen SOC bildet, die Kunden durch das Hinzuf\u00fcgen neuer Anwendungsbereiche speziell an die Anforderungen ihrer Organisation anpassen k\u00f6nnen. Ein Beispiel hierf\u00fcr sind die durch XSOAR-Funktionen erm\u00f6glichten Orchestrierungs- und automatisierten Behebungsma\u00dfnahmen und Funktionen f\u00fcr das Angriffsfl\u00e4chenmanagement mit Xpanse, die alle vollst\u00e4ndig in unsere KI-basierte Plattform Cortex XSIAM integriert sind.<\/p>\n<h2><a id=\"post-321685-_1fob9te\"><\/a>Die Cortex-Revolution<\/h2>\n<p>Der Einsatz von Cortex ist ein bew\u00e4hrtes Erfolgsrezept: Bedrohungen werden praktisch in Maschinengeschwindigkeit sehr schnell erkannt und in wenigen Minuten (statt wie fr\u00fcher mehreren Tagen) behoben. Beides ist f\u00fcr moderne SOCs unabdingbar und mit Cortex\u00a0XDR als Grundlage machbar. Kunden, die ihre Teams erg\u00e4nzen und unterst\u00fctzen m\u00f6chten, k\u00f6nnen sich an unsere\u00a0<a href=\"https:\/\/www.paloaltonetworks.com\/resources\/datasheets\/managed-detection-and-response\">geschulten XMDR-Partner wenden<\/a>\u00a0oder den<a href=\"https:\/\/www.paloaltonetworks.com\/unit42\/respond\/managed-detection-response\">Managed-Detection-and-Response(MDR)-Service<\/a>\u00a0unserer Unit\u00a042 in Anspruch nehmen.<\/p>\n<p>Die Anerkennung als Leader im Forrester Wave-Bericht f\u00fcr XDR ist f\u00fcr uns eine gro\u00dfe Ehre und wir verpflichten uns weiterhin dem Ziel, unseren Kunden die bestm\u00f6glichen Sicherheitsma\u00dfnahmen bereitzustellen.<\/p>\n<p>Laden Sie noch heute Ihr kostenloses Exemplar des Berichts\u00a0<a href=\"https:\/\/start.paloaltonetworks.com\/2024-forrester-xdr-wave-leader\">The Forrester Wave\u2122: Extended Detection And Response Platforms, Q2 2024<\/a>\u00a0herunter.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit Cortex\u00a0XDR wird Palo Alto Networks im Forrester Wave-Bericht 2024 f\u00fcr Extended-Detection-and-Response-Plattformen als Leader aufgef\u00fchrt. Seit unser Gr\u00fcnder Nir Zuk vor fast sechs Jahren den Begriff \u201eExtended Detection and Response\u201d (Erweiterte Bedrohungserkennung &hellip;<\/p>\n","protected":false},"author":758,"featured_media":321961,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8561,8562],"tags":[],"coauthors":[8381],"class_list":["post-324696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-announcement-de","category-products-and-services-de","sec_ops_category-must-read-articles-de","sec_ops_category-news-and-events-de","sec_ops_category-product-features-de"],"jetpack_featured_media_url":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2024\/06\/cortex-xdr_forrester-wave-report-2024_blog1_400x300.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/324696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/users\/758"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/comments?post=324696"}],"version-history":[{"count":1,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/324696\/revisions"}],"predecessor-version":[{"id":324697,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/324696\/revisions\/324697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/media\/321961"}],"wp:attachment":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/media?parent=324696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/categories?post=324696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/tags?post=324696"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/coauthors?post=324696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}