{"id":59392,"date":"2018-01-25T09:18:48","date_gmt":"2018-01-25T17:18:48","guid":{"rendered":"https:\/\/www.paloaltonetworks.com\/blog\/?p=59392"},"modified":"2018-01-25T09:26:11","modified_gmt":"2018-01-25T17:26:11","slug":"magnifier-para-el-analisis-de-comportamiento-caza-y-detiene-rapidamente-las-amenazas-de-red-mas-sigilosas","status":"publish","type":"post","link":"https:\/\/www2.paloaltonetworks.com\/blog\/2018\/01\/magnifier-para-el-analisis-de-comportamiento-caza-y-detiene-rapidamente-las-amenazas-de-red-mas-sigilosas\/?lang=es","title":{"rendered":"Magnifier para el an\u00e1lisis de comportamiento: caza y detiene r\u00e1pidamente las amenazas de red m\u00e1s sigilosas"},"content":{"rendered":"<p>En Palo Alto Networks siempre estamos buscando nuevas formas de cumplir nuestra misi\u00f3n: impedir que los ciberataques logren sus objetivos para proteger nuestro modo de vida en la era digital. Analizamos todos los pasos que realizan los autores de las amenazas para materializar sus ataques y a\u00f1adimos nuevos sistemas de protecci\u00f3n de forma sistem\u00e1tica para bloquear cada uno de ellos. Al paralizar los distintos movimientos de los autores de las amenazas, conseguimos limitar el n\u00famero de oportunidades de \u00e9xito de los ataques.<\/p>\n<p>Para reforzar la capacidad de detenci\u00f3n de amenazas de las organizaciones a lo largo de todo el ciclo de vida de los ataques, incluidos los m\u00e1s dif\u00edciles de detectar en la red, nos enorgullece presentar el <a href=\"https:\/\/www.paloaltonetworks.com\/company\/press\/2018\/palo-alto-networks-delivers-cloud-based-behavioral-analytics-with-introduction-of-magnifier\"><strong>an\u00e1lisis de comportamiento de Magnifier<\/strong><\/a>. Se trata de una aplicaci\u00f3n basada en la nube que analiza los datos recopilados desde la plataforma de seguridad de nueva generaci\u00f3n, realiza perfiles de comportamiento de los usuarios y los dispositivos en la red, y detecta anomal\u00edas de comportamiento que puedan sugerir la existencia de un ataque en curso.<\/p>\n<p>Pero Magnifier no se limita a esto. Tambi\u00e9n recopila informaci\u00f3n de gran valor de los endpoints sospechosos y la entrega en forma de alertas muy \u00fatiles, con datos sobre el contexto de los usuarios y los dispositivos. Los detalles que proporcionan las alertas permiten a los analistas de seguridad bloquear los ataques r\u00e1pidamente.<\/p>\n<p>Magnifier ofrece varias funciones principales para ayudar a los equipos de seguridad a localizar los ataques relevantes, responder a las amenazas con prontitud y superar los retos que conlleva la creaci\u00f3n de logs de grandes vol\u00famenes de datos. Entre estas funciones se incluyen las siguientes:<\/p>\n<ul>\n<li><strong>Detecci\u00f3n automatizada:<\/strong> Magnifier se basa en el aprendizaje autom\u00e1tico para analizar los datos de las redes de alta capacidad, los endpoints y la nube desde la <a href=\"https:\/\/www.paloaltonetworks.com\/products\/designing-for-prevention\/security-platform\">plataforma de seguridad de nueva generaci\u00f3n<\/a>, y realizar perfiles de comportamiento. A partir de esta informaci\u00f3n, Magnifier detecta anomal\u00edas de comportamiento que pueden indicar la presencia de tr\u00e1fico de comando y control, movimiento lateral y exfiltraci\u00f3n de datos. Asimismo, activa un peque\u00f1o n\u00famero de alertas muy precisas que revelan los ataques dirigidos, el uso fraudulento interno y la ejecuci\u00f3n de malware en los endpoints.<\/li>\n<li><strong>Respuesta acelerada:<\/strong> Magnifier analiza de forma din\u00e1mica los or\u00edgenes de los ataques para localizar los procesos en ejecuci\u00f3n, gracias a lo cual se precisa mucho menos tiempo para realizar la investigaci\u00f3n necesaria. A continuaci\u00f3n, examina los procesos sospechosos con el an\u00e1lisis de amenazas basado en la nube de <a href=\"https:\/\/www.paloaltonetworks.com\/products\/secure-the-network\/subscriptions\/wildfire\">WildFire<\/a> para detectar el malware. Los analistas de seguridad reciben informaci\u00f3n detallada en forma de alertas sobre usuarios, dispositivos y procesos de los endpoints, que les permite bloquear amenazas al instante con el <a href=\"https:\/\/www.paloaltonetworks.com\/products\/secure-the-network\/next-generation-firewall\">cortafuegos de nueva generaci\u00f3n<\/a> de Palo Alto Networks.<\/li>\n<li><strong>Escalabilidad y agilidad en la nube:<\/strong> al tratarse de una aplicaci\u00f3n basada en la nube, Magnifier consigue escalar los procesos locales de an\u00e1lisis sin ning\u00fan problema y permite a los investigadores de Palo Alto Networks implementar las innovaciones en seguridad con mayor rapidez. Asimismo, analiza los datos almacenados en nuestro <a href=\"https:\/\/www.paloaltonetworks.com\/products\/management\/logging-service\">servicio de creaci\u00f3n de logs<\/a>, que permite almacenar los grandes vol\u00famenes de datos necesarios para efectuar el an\u00e1lisis de comportamiento de un modo inteligente, econ\u00f3mico y operativamente eficaz. Magnifier tambi\u00e9n fomenta la innovaci\u00f3n, ya que los investigadores pueden implementar con rapidez nuevos algoritmos de detecci\u00f3n en todos los clientes de forma simult\u00e1nea, sin necesidad de superar largos ciclos de actualizaci\u00f3n de software y los retrasos que estos provocan.<\/li>\n<\/ul>\n<p>Los algoritmos de detecci\u00f3n que usa Magnifier no son nuevos, sino que se basan en la galardonada tecnolog\u00eda de LightCyber, una empresa que Palo Alto Networks adquiri\u00f3 en febrero de 2017.<\/p>\n<p>Ahora que la tecnolog\u00eda de an\u00e1lisis de comportamiento de LightCyber est\u00e1 integrada en la plataforma de seguridad de nueva generaci\u00f3n, nuestros resultados en materia de seguridad son a\u00fan mejores. Aprovechamos la potencia de la plataforma para utilizar un n\u00famero mayor de or\u00edgenes de datos en la detecci\u00f3n de ataques, incluida la informaci\u00f3n \u00fanica procedente de User-ID, App-ID y Content-ID, y el an\u00e1lisis de amenazas l\u00edder en el sector de WildFire. Como resultado, nuestros clientes consiguen bloquear los ataques r\u00e1pidamente gracias al cortafuegos de nueva generaci\u00f3n.<\/p>\n<p><div style=\"max-width:100%\" data-width=\"842\"><span class=\"ar-custom\" style=\"padding-bottom:39.79%;\"><img loading=\"lazy\" decoding=\"async\"  class=\"size-full wp-image-57508 aligncenter lozad\"  data-src=\"https:\/\/www.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/01\/Magnifier-1.png\" alt=\"Magnifier\" width=\"842\" height=\"335\" \/><\/span><\/div><\/p>\n<table width=\"475\">\n<tbody>\n<tr>\n<td width=\"238\"><em>Pathfinder Endpoint Interrogation<\/em><\/td>\n<td width=\"238\"><em>Consulta a los endpoints de Pathfinder<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"238\"><em>Campus Network<\/em><\/td>\n<td width=\"238\"><em>Red de campus<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"238\"><em>Pathfinder VM<\/em><\/td>\n<td width=\"238\"><em>Pathfinder VM<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"238\"><em>Data Center<\/em><\/td>\n<td width=\"238\"><em>Centro de datos<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"238\"><em>Cloud Data Center<\/em><\/td>\n<td width=\"238\"><em>Centro de datos en la nube<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"238\"><em>APPLICATION FRAMEWORK LOGGING SERVICE<\/em><\/td>\n<td width=\"238\"><em>SERVICIO DE CREACI\u00d3N DE LOGS DEL MARCO DE APLICACIONES<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"238\"><em>MAGNIFIER<\/em><\/td>\n<td width=\"238\"><em>MAGNIFIER<\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>Magnifier analiza los metadatos procedentes de los cortafuegos de nueva generaci\u00f3n y del servicio de an\u00e1lisis de endpoints Magnifier Pathfinder para detectar ataques activos.<\/em><\/p>\n<p>Acomp\u00e1\u00f1enos a lo largo de un recorrido que transformar\u00e1 el modo en que las organizaciones combaten los ataques que suceden a las intrusiones. Suscr\u00edbase a la <a href=\"https:\/\/www.paloaltonetworks.com\/products\/secure-the-network\/magnifier-behavioral-analytics\">primera aplicaci\u00f3n disponible<\/a> en el marco de aplicaciones de Palo Alto Networks.<\/p>\n<p><strong>Disponibilidad<\/strong><\/p>\n<p>Se prev\u00e9 que Magnifier estar\u00e1 disponible en febrero de 2018. P\u00f3ngase en contacto con su equipo de cuenta de Palo Alto Networks para averiguar si puede optar a la versi\u00f3n de prueba gratuita de Magnifier y disfrutar as\u00ed de una visibilidad sin precedentes de las amenazas que acechan su red.<\/p>\n<p><strong>Conozca mejor Magnifier: <\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.paloaltonetworks.com\/products\/secure-the-network\/magnifier-behavioral-analytics\">An\u00e1lisis de comportamiento de Magnifier<\/a><\/li>\n<li><a href=\"https:\/\/www.paloaltonetworks.com\/resources\/datasheets\/magnifier\">Ficha t\u00e9cnica de Magnifier<\/a><\/li>\n<li><a href=\"https:\/\/www.paloaltonetworks.com\/company\/press\/2018\/palo-alto-networks-delivers-cloud-based-behavioral-analytics-with-introduction-of-magnifier\">Comunicado de prensa de Magnifier<\/a><\/li>\n<li><a href=\"https:\/\/www.paloaltonetworks.com\/resources\/whitepapers\/esg-solution-showcase\">Informe t\u00e9cnico: Palo Alto Networks: C\u00f3mo compensar la carencia de habilidades en ciberseguridad con el an\u00e1lisis de comportamiento<\/a><\/li>\n<li><a href=\"http:\/\/players.brightcove.net\/1050259881001\/default_default\/index.html?videoId=5713094581001\" rel=\"nofollow,noopener\" >V\u00eddeo de pizarra transparente sobre Magnifier<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Magnifier para el an\u00e1lisis de comportamiento: caza y detiene r\u00e1pidamente las amenazas de red m\u00e1s sigilosas.<\/p>\n","protected":false},"author":370,"featured_media":57580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5040],"tags":[5266,5278,5230],"coauthors":[3907],"class_list":["post-59392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-analisis-de-comportamiento","tag-aprendizaje-automatico","tag-magnifier"],"jetpack_featured_media_url":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/01\/jyn-magnifier-blog-600x382-opb.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/59392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/users\/370"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/comments?post=59392"}],"version-history":[{"count":1,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/59392\/revisions"}],"predecessor-version":[{"id":59395,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/59392\/revisions\/59395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/media\/57580"}],"wp:attachment":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/media?parent=59392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/categories?post=59392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/tags?post=59392"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/coauthors?post=59392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}