{"id":67159,"date":"2018-03-13T02:00:32","date_gmt":"2018-03-13T09:00:32","guid":{"rendered":"https:\/\/www.paloaltonetworks.com\/blog\/?p=67159"},"modified":"2018-03-09T05:44:34","modified_gmt":"2018-03-09T13:44:34","slug":"av-test-validiert-traps-kann-veraltete-antivirus-produkte-ersetzen","status":"publish","type":"post","link":"https:\/\/www2.paloaltonetworks.com\/blog\/2018\/03\/av-test-validiert-traps-kann-veraltete-antivirus-produkte-ersetzen\/?lang=de","title":{"rendered":"AV-TEST validiert: Traps kann veraltete Antivirus-Produkte ersetzen"},"content":{"rendered":"<p>Unabh\u00e4ngige, glaubw\u00fcrdige Tests spielen eine entscheidende Rolle beim Treffen fundierter Kaufentscheidungen f\u00fcr neue Technologie. Traps\u2122, das Advanced\u00a0Endpoint\u00a0Protection-Angebot von Palo Alto Networks, wurde ausf\u00fchrlich von Dritten getestet, um seine St\u00e4rken als Ersatz f\u00fcr veraltete Antivirus-Produkte unter Beweis zu stellen.<\/p>\n<p><a href=\"https:\/\/www.av-test.org\/en\/\" rel=\"nofollow,noopener\" >AV-TEST<\/a>, ein Drittanbieterunternehmen f\u00fcr Sicherheitstests mit umfangreicher Erfahrung auf dem Gebiet von Endpunkt-Sicherheitssoftware \u2013 vor allem im Bereich veralteter Antivirus-Produkte \u2013 hat Traps\u2122 auf Herz und Nieren gepr\u00fcft. Es ist das erste Mal, dass Traps\u2122 von AV-TEST gepr\u00fcft wurde, und au\u00dferdem ist es das einzige Next-Generation-Produkt zum Schutz von Endprodukten, das 2017 von AV-Test unter die Lupe genommen wurde.<\/p>\n<p><a href=\"https:\/\/www.av-test.org\/fileadmin\/pdf\/reports\/AV-TEST_Palo_Alto_Traps_Full_Product_Test_July_2017.pdf\" rel=\"nofollow,noopener\" ><strong>AV-TEST-Ergebnisse anzeigen\u00a0<\/strong><\/a><\/p>\n<p>Die Ergebnisse haben eine \u00a0<strong>hundertprozentige Erkennung<\/strong>\u00a0realer Angriffe und ein maximales Leistungsergebnis gezeigt. AV-Test meinte dazu:\u00a0<em>\u201e\u2026 es gab nahezu keinen messbaren Einfluss auf das neuere System.\u201c<\/em>\u00a0Diese Ergebnisse wurden ohne jegliche Nutzung von Signaturen erzielt.<\/p>\n<p>Diese Validierung durch AV-TEST folgt auf die\u00a0<a href=\"https:\/\/www.paloaltonetworks.com\/resources\/whitepapers\/traps-advanced-endpoint-protection-av-comparatives-award\">Auszeichnung \u201eAV-Comparatives Approved Business Product\u201c, die Traps\u2122 im Oktober 2016 erhalten hat<\/a>. Dies ist eine Fortsetzung der Anstrengungen, auf die bereits bestehende Drittanbieterunterst\u00fctzung von Traps\u2122 aufzubauen. Werfen Sie einen Blick auf die weiteren Anerkennungen, die Traps\u2122 nach Sicherheitstests durch Drittparteien erhalten hat:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.paloaltonetworks.com\/resources\/whitepapers\/traps-advanced-endpoint-protection-named-visionary-gartner\">2017 im Gartner Magic Quadrant als vision\u00e4res Produkt f\u00fcr Endpunkte bezeichnet<\/a><\/li>\n<li><a href=\"http:\/\/www.crn.com\/slide-shows\/data-center\/300082998\/crns-2016-products-of-the-year.htm\/pgno\/0\/23\" rel=\"nofollow,noopener\" >Von CRN ausgezeichnet als Endpunkt-Sicherheitsprodukt des Jahres 2016<\/a><\/li>\n<li><a href=\"https:\/\/www.paloaltonetworks.com\/resources\/whitepapers\/traps-advanced-endpoint-protection-named-strong-performer-by-forrester-research\">In der Forrester-Rangliste leistungsstarker Produkte f\u00fcr Q4 2016 genannt<\/a><\/li>\n<li>PCI\/HIPAA-Compliance-Validierung von Coalfire\n<ul>\n<li><a href=\"https:\/\/www.paloaltonetworks.com\/resources\/whitepapers\/traps-advanced-endpoint-protection-pci-validation\">PCI-DSS-Compliance-Bericht<\/a><\/li>\n<li><a href=\"https:\/\/www.paloaltonetworks.com\/resources\/whitepapers\/traps-advanced-endpoint-protection-hipaa-validation\/\">HIPAA-Compliance-Bericht<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><div style=\"max-width:100%\" data-width=\"594\"><span class=\"ar-custom\" style=\"padding-bottom:49.83%;\"><img loading=\"lazy\" decoding=\"async\"  class=\"size-full wp-image-67162 lozad\"  data-src=\"https:\/\/www.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/03\/Traps-AV-Test.png\" alt=\"AV-TEST Validated: Traps Can Replace Legacy Antivirus\" width=\"594\" height=\"296\" \/><\/span><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unabh\u00e4ngige, glaubw\u00fcrdige Tests spielen eine entscheidende Rolle beim Treffen fundierter Kaufentscheidungen f\u00fcr neue Technologie. Traps\u2122, das Advanced\u00a0Endpoint\u00a0Protection-Angebot von Palo Alto Networks, wurde ausf\u00fchrlich von Dritten getestet, um seine St\u00e4rken als Ersatz f\u00fcr &hellip;<\/p>\n","protected":false},"author":40,"featured_media":67162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3549],"tags":[603,4153,193,778],"coauthors":[716],"class_list":["post-67159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","tag-advanced-endpoint-protection","tag-av-test","tag-palo-alto-networks","tag-traps"],"jetpack_featured_media_url":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/03\/Traps-AV-Test.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/67159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/comments?post=67159"}],"version-history":[{"count":1,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/67159\/revisions"}],"predecessor-version":[{"id":67201,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/67159\/revisions\/67201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/media\/67162"}],"wp:attachment":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/media?parent=67159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/categories?post=67159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/tags?post=67159"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/coauthors?post=67159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}