{"id":94602,"date":"2018-11-19T02:17:18","date_gmt":"2018-11-19T10:17:18","guid":{"rendered":"https:\/\/www.paloaltonetworks.com\/blog\/?p=94602"},"modified":"2018-11-19T02:17:18","modified_gmt":"2018-11-19T10:17:18","slug":"report-sulle-minacce-documenti-di-office-possono-essere-pericolosi-ma-continueremo-usarli","status":"publish","type":"post","link":"https:\/\/www2.paloaltonetworks.com\/blog\/2018\/11\/report-sulle-minacce-documenti-di-office-possono-essere-pericolosi-ma-continueremo-usarli\/?lang=it","title":{"rendered":"REPORT SULLE MINACCE: I DOCUMENTI DI OFFICE POSSONO ESSERE PERICOLOSI (ma continueremo a usarli)"},"content":{"rendered":"<p>Tutti noi utilizziamo documenti di Microsoft Office. Ci occorrono per lavoro, come ricevute elettroniche, per un contratto di affitto. Anche per questo motivo, con ogni probabilit\u00e0, apriremo un documento di Office ricevuto in allegato nella nostra email. Consapevoli che molti di noi apriranno qualsiasi tipo di documento, anche quelli provenienti da fonti non attendibili, i criminali informatici scelgono spesso questi file per attaccare e compromettere un sistema.<\/p>\n<p>In questo report, illustriamo cinque diverse modalit\u00e0 di manipolazione fraudolenta dei documenti di Office, utilizzate per attaccare e compromettere un endpoint Windows. Di alcune abbiamo gi\u00e0 scritto in precedenza, altre sono inedite.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Macro<\/strong><\/p>\n<p>Per un criminale informatico, le macro sono il metodo pi\u00f9 immediato per utilizzare i documenti di Office come arma. Le applicazioni di Office hanno un motore integrato che pu\u00f2 eseguire script VBA (Visual Basic for Applications). L'esecuzione di uno script, contenente codice maligno, pu\u00f2 avvenire anche all'apertura del documento, senza alcuna interazione dell'utente (se le macro sono state in precedenza abilitate). Se l'utente non ha abilitato le macro, una finestra pop-up chiede all'utente di farlo con un clic. La finestra pop-up \u00e8 uno dei vari meccanismi di sicurezza introdotti da Microsoft per ridurre il rischio associato alle macro. Microsoft impone anche una diversa estensione del file (.docm invece di .docx) per i nuovi documenti che contengono macro. Nonostante queste misure, gli utenti continuano ad aprire questi file e ad abilitarne il contenuto. Le macro rimangono tuttora un comune vettore di attacco, sia per infezioni ransomware semplici e generiche come <a href=\"https:\/\/autofocus.paloaltonetworks.com\/#\/tag\/Unit42.Emotet\">Emotet<\/a>, sia per azioni pi\u00f9 sofisticate come quella della <a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2018\/02\/unit42-sofacy-attacks-multiple-government-entities\/\">campagna Sofacy<\/a>.<\/p>\n<p><div style=\"max-width:100%\" data-width=\"837\"><span class=\"ar-custom\" style=\"padding-bottom:97.01%;\"><img loading=\"lazy\" decoding=\"async\"  class=\"alignnone size-full wp-image-92538 lozad\"  data-src=\"https:\/\/www.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN.png\" alt=\"\" width=\"837\" height=\"812\" srcset=\"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN.png 837w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-230x223.png 230w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-768x745.png 768w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-500x485.png 500w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-309x300.png 309w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-41x40.png 41w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-32x32.png 32w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-50x50.png 50w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/span><\/div><\/p>\n<p>Figura 1. Il documento Sofacy prima e dopo l'abilitazione del contenuto<\/p>\n<p>Come si vede nell'esempio, i criminali inducono gli utenti a disabilitare i meccanismi di sicurezza introdotti da Microsoft utilizzando l'ingegneria sociale, promettendo di mostrare l'intero documento solo se si accetta di abilitare i contenuti. Nell'esempio Sofacy, i criminali hanno semplicemente scelto il bianco come colore del font. Il testo \u00e8 quindi gi\u00e0 presente prima dell'abilitazione delle macro ma \u00e8 stato reso invisibile.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>File Flash incorporati<\/strong><\/p>\n<p>Oltre a funzionalit\u00e0 native come le macro, i documenti di Office possono anche incorporare oggetti esterni come i file di Adobe Flash. La gestione di questi oggetti viene delegata al software di origine. In tal modo, qualsiasi vulnerabilit\u00e0 di Adobe Flash pu\u00f2 essere sfruttata per un attacco dal contenuto incorporato nel documento Office. Un tale vettore di attacco \u00e8 stato utilizzato su <u><a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2018\/02\/unit42-traps-prevents-adobe-flash-player-zero-day\/\">CVE-2018-4878<\/a><\/u>, una falla Zero-Day di Adobe Flash Player sfruttata da file nocivi SWF incorporati in documenti Excel. In questi tipi di attacchi, i file Excel incorporano contenuti Adobe Flash che sfruttano la vulnerabilit\u00e0 di Flash per eseguire un codice shell nocivo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Microsoft Equation Editor<\/strong><\/p>\n<p>Analogamente a quanto visto per i file di Adobe Flash, i documenti di Office possono anche incorporare oggetti creati da Microsoft Equation Editor, un programma che permette di scrivere equazioni matematiche.<\/p>\n<p><div style=\"max-width:100%\" data-width=\"893\"><span class=\"ar-custom\" style=\"padding-bottom:53.08%;\"><img loading=\"lazy\" decoding=\"async\"  class=\"alignnone size-full wp-image-92577 lozad\"  data-src=\"https:\/\/www.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN.png\" alt=\"\" width=\"893\" height=\"474\" srcset=\"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN.png 893w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-230x122.png 230w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-768x408.png 768w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-500x265.png 500w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-510x271.png 510w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-75x40.png 75w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-565x300.png 565w\" sizes=\"auto, (max-width: 893px) 100vw, 893px\" \/><\/span><\/div><\/p>\n<p>Figura 2. \u00a0Microsoft Equation Editor<\/p>\n<p>Come nell'esempio precedente, le vulnerabilit\u00e0 dell'Equation Editor possono essere sfruttate attraverso i documenti di Office. Abbiamo visto recentemente esempi del genere, con l'exploit della vulnerabilit\u00e0 <u><a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2017\/12\/unit42-analysis-of-cve-2017-11882-exploit-in-the-wild\/\">CVE-2017-11882<\/a><\/u> che ha preparato la strada ad altri attacchi, come <u><a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2018\/01\/unit42-traps-prevents-microsoft-office-equation-editor-zero-day-cve-2017-11882\/\">CVE-2018-0802<\/a><\/u>. In entrambi i casi, vengono sfruttate falle nell'Equation Editor, che permettono ai criminali di eseguire codice remoto quando il documento di Office viene aperto dall'utente. Anche se non sono state sfruttate, simili vulnerabilit\u00e0 in Microsoft Equation Editor, come la <u><a href=\"https:\/\/portal.msrc.microsoft.com\/en-US\/security-guidance\/advisory\/CVE-2018-0807\" rel=\"nofollow,noopener\" >CVE-2018-0807<\/a><\/u> e la <u><a href=\"https:\/\/portal.msrc.microsoft.com\/en-US\/security-guidance\/advisory\/CVE-2018-0798\" rel=\"nofollow,noopener\" >CVE-2018-0798<\/a><\/u>, sono state identificate dai ricercatori di Unit 42.<\/p>\n<p>Occorre sottolineare che Microsoft Equation Editor esegue un processo a s\u00e9 stante (eqnedt32.exe), pertanto protezioni specifiche per Microsoft Office come EMET e Windows Defender Exploit Guard non sono efficaci in impostazione predefinita, poich\u00e9 proteggono solo i processi di Office (come winword.exe).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Oggetti OLE e gestori HTA<\/strong><\/p>\n<p>Gli oggetti OLE e gli handler HTA sono meccanismi utilizzati dai documenti Office per fare riferimento ad altri documenti da includere nel loro contenuto. Possono essere utilizzati per compromettere un endpoint in questo modo:<\/p>\n<ul>\n<li>Un documento Microsoft Word \u00e8 incorporato tramite un oggetto link OLE2<\/li>\n<li>Una volta aperto il documento, il processo Word (winword.exe) invia una richiesta HTTP a un server remoto per prelevare un file HTA con uno script nocivo<\/li>\n<li>exe cerca quindi il gestore file per l\u2019applicazione\/hta tramite un oggetto COM, che chiede all'applicazione HTA di Microsoft (mshta.exe) di caricare ed eseguire lo script nocivo.<\/li>\n<\/ul>\n<p>Questa funzionalit\u00e0 \u00e8 stata usata nell'exploit della <u><a href=\"https:\/\/portal.msrc.microsoft.com\/en-US\/security-guidance\/advisory\/CVE-2017-0199\" rel=\"nofollow,noopener\" >CVE-2017-0199<\/a><\/u>, una vulnerabilit\u00e0 nell'esecuzione di codice remoto (RCE) di Microsoft Office\/WordPad, risolta da Microsoft con una patch nel settembre 2017 e sfruttata in diversi attacchi, come nella <a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2017\/10\/unit42-oilrig-group-steps-attacks-new-delivery-documents-new-injector-trojan\/\">campagna OilRig<\/a>.<\/p>\n<p><div style=\"max-width:100%\" data-width=\"337\"><span class=\"ar-custom\" style=\"padding-bottom:40.06%;\"><img loading=\"lazy\" decoding=\"async\"  class=\"alignnone size-full wp-image-92616 lozad\"  data-src=\"https:\/\/www.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage3zhCN.png\" alt=\"\" width=\"337\" height=\"135\" srcset=\"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage3zhCN.png 337w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage3zhCN-230x92.png 230w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage3zhCN-100x40.png 100w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/span><\/div><\/p>\n<p>Figura 3. I file RTF appaiono esattamente come normali documenti Word<\/p>\n<p>Oltre alla citata vulnerabilit\u00e0 OLE &amp; HTA, i criminali hanno scoperto che anche i file RTF possono eseguire oggetti OLE di tipo mime 'text\/html' utilizzando il MSHTML. Ci\u00f2 significa che i file RTF espongono la stessa superficie di attacco di Internet Explorer.<\/p>\n<p>Sfruttando questa vulnerabilit\u00e0 logica, nota come <u><a href=\"https:\/\/portal.msrc.microsoft.com\/en-US\/security-guidance\/advisory\/CVE-2018-8174\" rel=\"nofollow,noopener\" >CVE-2018-8174<\/a><\/u>, i criminali informatici possono eseguire codice arbitrario HTML\/JavaScript\/VBScript. Anche se tale codice \u00e8 eseguito in una \"sandbox\" (non pu\u00f2 eseguire nuovi processi, scrivere nel filesystem, ecc.), come altro codice eseguito da Internet Explorer, questa falla pu\u00f2 essere usata per sfruttare altre vulnerabilit\u00e0, come una corruzione di memoria UAF nel motore VBScript, per eseguire codice arbitrario nel contesto dell'applicazione Word (winword.exe), e quindi prendere controllo del sistema.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Conclusione<\/strong><\/p>\n<p>Nonostante gli attacchi basati sui documenti siano abbastanza comuni da una decina d'anni, abbiamo recentemente assistito a una crescita della loro frequenza e complessit\u00e0. Tale crescita \u00e8 forse dovuta al fatto che gli exploit sui browser sono diventati pi\u00f9 difficili, per effetto delle misure di sicurezza adottate da questi software. A prescindere dalle ragioni, \u00e8 essenziale che le aziende sappiano come difendersi da queste tecniche comuni.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Prevenzione<\/strong><\/p>\n<p>Traps Advanced Endpoint Protection di Palo Alto Networks offre diversi metodi di prevenzione da malware ed exploit per respingere queste minacce:<\/p>\n<ul>\n<li>Analisi delle macro: Traps esamina ogni documento di Office alla ricerca di macro nocive utilizzando sia il cloud di intelligenza delle minacce WildFire, sia le funzionalit\u00e0 locali di machine learning e pu\u00f2 anche impedire all'utente di aprire i file maligni.<\/li>\n<li>Prevenzione degli exploit: le ampie funzionalit\u00e0 di prevenzione degli exploit di Traps neutralizzano i tentativi di attacco impedendo che il codice shell nocivo sia eseguito sull'endpoint.<\/li>\n<li>Per impostazione predefinita, Traps si occupa del monitoraggio delle applicazioni di Office e assicura che i processi legittimi non siano sfruttati per attivit\u00e0 illegali.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Tutti noi utilizziamo documenti di Microsoft Office. Ci occorrono per lavoro, come ricevute elettroniche, per un contratto di affitto. Anche per questo motivo, con ogni probabilit\u00e0, apriremo un documento di Office ricevuto &hellip;<\/p>\n","protected":false},"author":575,"featured_media":67267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5085],"tags":[],"coauthors":[6203],"class_list":["post-94602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"jetpack_featured_media_url":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2017\/03\/Linkedin.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/94602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/users\/575"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/comments?post=94602"}],"version-history":[{"count":1,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/94602\/revisions"}],"predecessor-version":[{"id":94603,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/94602\/revisions\/94603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/media\/67267"}],"wp:attachment":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/media?parent=94602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/categories?post=94602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/tags?post=94602"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/coauthors?post=94602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}