{"id":94611,"date":"2018-11-19T02:44:36","date_gmt":"2018-11-19T10:44:36","guid":{"rendered":"https:\/\/www.paloaltonetworks.com\/blog\/?p=94611"},"modified":"2018-11-19T02:44:36","modified_gmt":"2018-11-19T10:44:36","slug":"informe-sobre-amenazas-los-documentos-de-office-pueden-ser-peligrosos-pero-seguiremos-usandolos","status":"publish","type":"post","link":"https:\/\/www2.paloaltonetworks.com\/blog\/2018\/11\/informe-sobre-amenazas-los-documentos-de-office-pueden-ser-peligrosos-pero-seguiremos-usandolos\/?lang=es","title":{"rendered":"Informe sobre amenazas: los documentos de Office pueden ser peligrosos (pero seguiremos us\u00e1ndolos)"},"content":{"rendered":"<p>Pr\u00e1cticamente todos utilizamos archivos de Microsoft\u00a0Office, ya se trate de documentos de trabajo, recibos electr\u00f3nicos o un contrato de alquiler. Nos resultan \u00fatiles en muchas ocasiones y este es uno de los motivos por los que, si nos llegan adjuntos a un mensaje de correo electr\u00f3nico, la probabilidad de que los abramos es bastante alta. As\u00ed, sabiendo que mucha gente abre pr\u00e1cticamente cualquier documento de este tipo aunque proceda de una fuente no fiable, los adversarios eligen con frecuencia estos archivos para poner en riesgo la seguridad de un sistema.<\/p>\n<p>En este informe exponemos cinco maneras en que se pueden subvertir y usar de forma maliciosa para atacar y poner en riesgo la seguridad de endpoints Windows. Algunas ya las hemos comentado en otras ocasiones, mientras que otras son nuevas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Macros<\/strong><\/p>\n<p>Utilizar macros es la forma m\u00e1s directa de convertir un documento de Office en un arma de ataque. Las aplicaciones de Office tienen un motor de scripts integrado capaz de ejecutar scripts de VBA (Visual Basic para Aplicaciones) en cuanto se abre el documento sin que el usuario haga nada (siempre que las macros est\u00e9n habilitadas), con lo que se pueden aprovechar para ejecutar c\u00f3digo malicioso. Si las macros no est\u00e1n habilitadas, aparecer\u00e1 una ventana emergente para pedir al usuario que las habilite. Estas ventanas emergentes constituyen uno de los mecanismos de seguridad que ha a\u00f1adido Microsoft para reducir el riesgo que suponen las macros. Adem\u00e1s, Microsoft utiliza una extensi\u00f3n de archivo diferente (.docm en lugar de .docx) para los nuevos documentos con macros. Sin embargo, a pesar de estas medidas de seguridad, hay usuarios que deciden abrir estos archivos y habilitar su contenido, con lo que las macros siguen siendo un vector de ataque habitual, ya sea para lanzar ataques sencillos con ransomware, como <a href=\"https:\/\/autofocus.paloaltonetworks.com\/#\/tag\/Unit42.Emotet\">Emotet<\/a>, o con campa\u00f1as avanzadas, como\u00a0<a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2018\/02\/unit42-sofacy-attacks-multiple-government-entities\/\">Sofacy<\/a>.<\/p>\n<p><div style=\"max-width:100%\" data-width=\"837\"><span class=\"ar-custom\" style=\"padding-bottom:97.01%;\"><img loading=\"lazy\" decoding=\"async\"  class=\"alignnone size-full wp-image-92538 lozad\"  data-src=\"https:\/\/www.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN.png\" alt=\"\" width=\"837\" height=\"812\" srcset=\"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN.png 837w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-230x223.png 230w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-768x745.png 768w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-500x485.png 500w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-309x300.png 309w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-41x40.png 41w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-32x32.png 32w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage1zhCN-50x50.png 50w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/span><\/div><\/p>\n<p>Figura 1. El documento de Sofacy antes y despu\u00e9s de habilitar el contenido.<\/p>\n<p>Como se ve en este ejemplo, los atacantes recurren a t\u00e9cnicas de ingenier\u00eda social para convencer a los usuarios de que desactiven los mecanismos de seguridad de Microsoft si quieren ver todo el documento. En el ejemplo de Sofacy, los atacantes simplemente hab\u00edan utilizado el blanco como color de la letra, as\u00ed que el texto ya estaba presente antes de habilitar las macros, solo que no se ve\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Archivos de Flash incrustados<\/strong><\/p>\n<p>Los documentos de Office, adem\u00e1s de capacidades integradas como las macros, tambi\u00e9n pueden incluir objetos externos incrustados, como archivos de Adobe Flash. Estos objetos se pasan al software oportuno para que los procese, con lo que cualquier vulnerabilidad que tenga dicho software tambi\u00e9n se podr\u00e1 aprovechar incrust\u00e1ndola dentro del contenido de Adobe Flash que haya en el documento de Office. Un ejemplo de uso de este tipo de vector de ataque es\u00a0<u><a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2018\/02\/unit42-traps-prevents-adobe-flash-player-zero-day\/\">CVE-2018-4878<\/a><\/u>, una vulnerabilidad de d\u00eda cero de Adobe Flash Player que se aprovech\u00f3 incrustando archivos SWF maliciosos en documentos de Excel. En los ataques de este tipo, el archivo de Excel malicioso lleva incrustado contenido de Adobe Flash que puede activar la vulnerabilidad de Flash y ejecutar el c\u00f3digo shell incrustado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Editor de ecuaciones de Microsoft<\/strong><\/p>\n<p>Del mismo modo que se pueden incrustar archivos de Adobe Flash en un documento de Office, tambi\u00e9n es posible incrustar ecuaciones en documentos que se vayan a procesar con el editor de ecuaciones de Microsoft, un programa que permite escribir ecuaciones matem\u00e1ticas con facilidad.<\/p>\n<p><div style=\"max-width:100%\" data-width=\"893\"><span class=\"ar-custom\" style=\"padding-bottom:53.08%;\"><img loading=\"lazy\" decoding=\"async\"  class=\"alignnone size-full wp-image-92577 lozad\"  data-src=\"https:\/\/www.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN.png\" alt=\"\" width=\"893\" height=\"474\" srcset=\"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN.png 893w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-230x122.png 230w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-768x408.png 768w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-500x265.png 500w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-510x271.png 510w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-75x40.png 75w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage2zhCN-565x300.png 565w\" sizes=\"auto, (max-width: 893px) 100vw, 893px\" \/><\/span><\/div><\/p>\n<p>Figura 2. \u00a0Editor de ecuaciones de Microsoft<\/p>\n<p>Como en el ejemplo anterior, se pueden aprovechar vulnerabilidades del editor de ecuaciones mediante documentos maliciosos de Office. Se han visto casos recientemente, como cuando se aprovech\u00f3 la vulnerabilidad\u00a0<u><a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2017\/12\/unit42-analysis-of-cve-2017-11882-exploit-in-the-wild\/\">CVE-2017-11882<\/a><\/u>, que allan\u00f3 el camino para otros exploits como\u00a0<u><a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2018\/01\/unit42-traps-prevents-microsoft-office-equation-editor-zero-day-cve-2017-11882\/\">CVE-2018-0802<\/a><\/u>. En ambos casos, los atacantes aprovechan fallos en el editor de ecuaciones para ejecutar un c\u00f3digo de forma remota cuando el usuario abre un documento de Office. Aunque a\u00fan no se han observado en acci\u00f3n, los investigadores de Unit\u00a042 han detectado exploits similares en el editor de ecuaciones de Microsoft, como\u00a0<u><a href=\"https:\/\/portal.msrc.microsoft.com\/en-US\/security-guidance\/advisory\/CVE-2018-0807\" rel=\"nofollow,noopener\" >CVE-2018-0807<\/a><\/u>\u00a0y\u00a0<u><a href=\"https:\/\/portal.msrc.microsoft.com\/en-US\/security-guidance\/advisory\/CVE-2018-0798\" rel=\"nofollow,noopener\" >CVE-2018-0798<\/a><\/u>.<\/p>\n<p>Cabe se\u00f1alar que, como el editor de ecuaciones de Microsoft ejecuta su propio proceso (eqnedt32.exe), los mecanismos de protecci\u00f3n espec\u00edficos para Microsoft Office, como EMET y Windows Defender, no son eficaces de forma predeterminada, pues solo protegen los procesos de Microsoft Office (como winword.exe).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Objetos OLE y controladores HTA<\/strong><\/p>\n<p>Los objetos OLE y los controladores HTA son mecanismos que utilizan los documentos de Office para incluir otros documentos en su contenido mediante referencias. Se pueden utilizar para comprometer un endpoint del siguiente modo:<\/p>\n<ul>\n<li>Se incrusta un objeto OLE2 en un documento de Microsoft Word.<\/li>\n<li>Una vez abierto el documento, el proceso de Word (winword.exe) env\u00eda una solicitud HTTP a un servidor remoto para recuperar un archivo HTA que contiene un script malicioso.<\/li>\n<li>A continuaci\u00f3n, winword.exe buscar\u00e1 la aplicaci\u00f3n\/HTA en el controlador de archivos mediante un objeto COM, lo que hace que la aplicaci\u00f3n HTA de Microsoft (mshta.exe) se cargue y ejecute el script malicioso.<\/li>\n<\/ul>\n<p>Esto fue lo que ocurri\u00f3 cuando se aprovech\u00f3 la vulnerabilidad\u00a0de ejecuci\u00f3n remota de c\u00f3digo <u><a href=\"https:\/\/portal.msrc.microsoft.com\/en-US\/security-guidance\/advisory\/CVE-2017-0199\" rel=\"nofollow,noopener\" >CVE-2017-0199<\/a><\/u>,\u00a0un fallo de Microsoft Office\/WordPad utilizado en distintas campa\u00f1as, como la de\u00a0<a href=\"https:\/\/www.paloaltonetworks.com\/blog\/2017\/10\/unit42-oilrig-group-steps-attacks-new-delivery-documents-new-injector-trojan\/\">OilRig<\/a>. Microsoft cre\u00f3 un parche para esta vulnerabilidad en septiembre de 2017.<\/p>\n<p><div style=\"max-width:100%\" data-width=\"337\"><span class=\"ar-custom\" style=\"padding-bottom:40.06%;\"><img loading=\"lazy\" decoding=\"async\"  class=\"alignnone size-full wp-image-92616 lozad\"  data-src=\"https:\/\/www.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage3zhCN.png\" alt=\"\" width=\"337\" height=\"135\" srcset=\"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage3zhCN.png 337w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage3zhCN-230x92.png 230w, https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2018\/10\/WordDocImage3zhCN-100x40.png 100w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/span><\/div><\/p>\n<p>Figura 3. Los archivos RTF tendr\u00e1n exactamente el mismo aspecto que los documentos de Word normales.<\/p>\n<p>Adem\u00e1s de los anteriores exploits contra OLE y HTA, los atacantes descubrieron que los archivos RTF tambi\u00e9n pueden ejecutar objetos OLE tipo MIME de texto\/html mediante MSHTML. \u00a1Esto significa que los documentos RTF exponen la misma superficie de ataque que Internet Explorer!<\/p>\n<p>Esta vulnerabilidad l\u00f3gica, conocida como\u00a0<u><a href=\"https:\/\/portal.msrc.microsoft.com\/en-US\/security-guidance\/advisory\/CVE-2018-8174\" rel=\"nofollow,noopener\" >CVE-2018-8174<\/a><\/u>, permite a los atacantes ejecutar c\u00f3digo HTML\/JavaScript\/VBScript arbitrario. Aunque el c\u00f3digo que se ejecuta de este modo queda en un espacio aislado (donde no pueda ejecutar nuevos procesos, escribir en el sistema de archivos, etc.), como el c\u00f3digo que se ejecuta desde Internet Explorer, este fallo se puede usar para aprovechar otras vulnerabilidades, como la vulnerabilidad UAF de corrupci\u00f3n de la memoria del motor VBScript, para ejecutar c\u00f3digo arbitrario en la aplicaci\u00f3n Word (winword.exe) y lograr as\u00ed controlar el sistema.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Conclusi\u00f3n<\/strong><\/p>\n<p>Aunque el uso de documentos para atacar es una pr\u00e1ctica habitual desde hace m\u00e1s de una d\u00e9cada, \u00faltimamente est\u00e1 aumentando la frecuencia y la complejidad de este tipo de ataques, tal vez porque cada vez es m\u00e1s dif\u00edcil atacar con exploits a los navegadores gracias a los avances de su seguridad. Sea cual sea el motivo de este aumento, es importante que las organizaciones sepan defenderse de estas t\u00e9cnicas tan habituales.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Prevenci\u00f3n<\/strong><\/p>\n<p>La protecci\u00f3n avanzada de endpoints de Traps de Palo Alto Networks ofrece varias formas de prevenci\u00f3n contra el malware y los exploits:<\/p>\n<ul>\n<li>An\u00e1lisis de macros: Traps recurre a la Threat Intelligence Cloud de WildFire y a capacidades locales de aprendizaje autom\u00e1tico para analizar los documentos de Office y detectar macros maliciosas. De este modo, evita que el usuario abra archivos maliciosos.<\/li>\n<li>Prevenci\u00f3n contra exploits: gracias a sus amplias capacidades de prevenci\u00f3n contra exploits, Traps evita que se ejecute shellcode malicioso en el endpoint atacado.<\/li>\n<li>De forma predeterminada, Traps supervisa las aplicaciones de Office y comprueba que no se aprovechen procesos integrados leg\u00edtimos para fines maliciosos.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e1cticamente todos utilizamos archivos de Microsoft\u00a0Office, ya se trate de documentos de trabajo, recibos electr\u00f3nicos o un contrato de alquiler. Nos resultan \u00fatiles en muchas ocasiones y este es uno de los &hellip;<\/p>\n","protected":false},"author":575,"featured_media":67273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5040],"tags":[],"coauthors":[6203],"class_list":["post-94611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"jetpack_featured_media_url":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-content\/uploads\/2017\/03\/Linkedin.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/94611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/users\/575"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/comments?post=94611"}],"version-history":[{"count":1,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/94611\/revisions"}],"predecessor-version":[{"id":94612,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/posts\/94611\/revisions\/94612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/media\/67273"}],"wp:attachment":[{"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/media?parent=94611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/categories?post=94611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/tags?post=94611"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www2.paloaltonetworks.com\/blog\/wp-json\/wp\/v2\/coauthors?post=94611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}